{"id":108,"count":1,"description":"","link":"https:\/\/eksam.id\/blog\/tag\/generasi-digital\/","name":"generasi digital","slug":"generasi-digital","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>generasi digital Archives - EKSAM.ID<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"generasi digital Archives - EKSAM.ID\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eksam.id\/blog\/tag\/generasi-digital\/\" \/>\n<meta property=\"og:site_name\" content=\"EKSAM.ID\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eksam.id\/blog\/wp-content\/uploads\/2022\/01\/logo_hitam.png\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"242\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@eksam_id\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/tag\\\/generasi-digital\\\/\",\"url\":\"https:\\\/\\\/eksam.id\\\/blog\\\/tag\\\/generasi-digital\\\/\",\"name\":\"generasi digital Archives - EKSAM.ID\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/eksam.id\\\/blog\\\/\",\"name\":\"EKSAM.ID\",\"description\":\"Teman Belajar Kamu\",\"publisher\":{\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eksam.id\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/#organization\",\"name\":\"EKSAM.ID\",\"url\":\"https:\\\/\\\/eksam.id\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eksam.id\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_hitam.png\",\"contentUrl\":\"https:\\\/\\\/eksam.id\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo_hitam.png\",\"width\":950,\"height\":242,\"caption\":\"EKSAM.ID\"},\"image\":{\"@id\":\"https:\\\/\\\/eksam.id\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eksam.id\",\"https:\\\/\\\/x.com\\\/eksam_id\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"generasi digital Archives - EKSAM.ID","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"generasi digital Archives - EKSAM.ID","og_url":"https:\/\/eksam.id\/blog\/tag\/generasi-digital\/","og_site_name":"EKSAM.ID","og_image":[{"width":950,"height":242,"url":"https:\/\/eksam.id\/blog\/wp-content\/uploads\/2022\/01\/logo_hitam.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@eksam_id","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/eksam.id\/blog\/tag\/generasi-digital\/","url":"https:\/\/eksam.id\/blog\/tag\/generasi-digital\/","name":"generasi digital Archives - EKSAM.ID","isPartOf":{"@id":"https:\/\/eksam.id\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/eksam.id\/blog\/#website","url":"https:\/\/eksam.id\/blog\/","name":"EKSAM.ID","description":"Teman Belajar Kamu","publisher":{"@id":"https:\/\/eksam.id\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eksam.id\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eksam.id\/blog\/#organization","name":"EKSAM.ID","url":"https:\/\/eksam.id\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eksam.id\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/eksam.id\/blog\/wp-content\/uploads\/2022\/01\/logo_hitam.png","contentUrl":"https:\/\/eksam.id\/blog\/wp-content\/uploads\/2022\/01\/logo_hitam.png","width":950,"height":242,"caption":"EKSAM.ID"},"image":{"@id":"https:\/\/eksam.id\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eksam.id","https:\/\/x.com\/eksam_id"]}]}},"_links":{"self":[{"href":"https:\/\/eksam.id\/blog\/wp-json\/wp\/v2\/tags\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eksam.id\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/eksam.id\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/eksam.id\/blog\/wp-json\/wp\/v2\/posts?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}